{"id":2551,"date":"2026-07-11T13:34:00","date_gmt":"2026-07-11T19:34:00","guid":{"rendered":"https:\/\/calvarymaranatha.com\/?p=2551"},"modified":"2026-07-11T14:00:37","modified_gmt":"2026-07-11T20:00:37","slug":"dones","status":"publish","type":"post","link":"https:\/\/calvarymaranatha.com\/en\/2026\/07\/11\/dones\/","title":{"rendered":"Los Dones Espirituales"},"content":{"rendered":"<div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--has-col-background vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-b81d89e4\" data-vce-do-apply=\"all el-b81d89e4\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-element--has-background vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-f3379be2\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-f3379be2\"><div class=\"vce-content-background-container\"><\/div><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-f3379be2\"><div class=\"vce-yt-video-player vce-yt-video-player--align-center vce-yt-video-player--size-560x315\"><div class=\"vce vce-yt-video-player-wrapper\" id=\"el-6babca8e\" data-vce-do-apply=\"all el-6babca8e\" style=\"width: 560px;\"><div class=\"vce-yt-video-player-inner\"><iframe loading=\"lazy\" class=\"vce-yt-video-player-iframe\" src=\"https:\/\/www.youtube.com\/embed\/-_JMawKB_cI?autoplay=0&amp;mute=0&amp;color=red&amp;controls=1&amp;loop=0&amp;rel=0&amp;start=0&amp;cc_load_policy=0&amp;iv_load_policy=3&amp;enablejsapi=1\" width=\"640\" height=\"390\" allowfullscreen=\"\" title=\"YouTube video\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-3b9abc41\" data-vce-do-apply=\"all el-3b9abc41\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-86034eef\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-86034eef\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-86034eef\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-e9db1b10\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-e9db1b10\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-e9db1b10\"><div class=\"vce-google-fonts-heading vce-google-fonts-heading--align-center vce-google-fonts-heading--color-empty--45--5C00FF--FF7200 vce-google-fonts-heading--font-family-Lato\"><div id=\"el-11c43ac1\" class=\"vce-google-fonts-heading-wrapper\"><div class=\"vce-google-fonts-heading--background vce\" data-vce-do-apply=\"border background  padding margin el-11c43ac1\"><h2 class=\"vce-google-fonts-heading-inner\" style=\"font-weight: 400; font-style: normal;\">Introducci\u00f3n<\/h2><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-11dd94f3\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-11dd94f3\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-11dd94f3\"><div class=\"vce-google-fonts-heading vce-google-fonts-heading--align-center vce-google-fonts-heading--color-empty--45--5C00FF--FF7200 vce-google-fonts-heading--font-family-Lato\"><div id=\"el-0fa4f0c7\" class=\"vce-google-fonts-heading-wrapper\"><div class=\"vce-google-fonts-heading--background vce\" data-vce-do-apply=\"border background  padding margin el-0fa4f0c7\"><h2 class=\"vce-google-fonts-heading-inner\" style=\"font-weight: 400; font-style: normal;\">Profec\u00eda y Servicio<\/h2><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-be4c16f8\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-be4c16f8\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-be4c16f8\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last\" id=\"el-e36e0d75\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-e36e0d75\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-e36e0d75\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-35f6993f\" data-vce-do-apply=\"all el-35f6993f\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-01326b88\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-01326b88\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-01326b88\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-4ad6ebe4\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-4ad6ebe4\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-4ad6ebe4\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-2917aa01\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-2917aa01\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-2917aa01\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-39146fd6\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-39146fd6\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-39146fd6\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last\" id=\"el-9fe95f9f\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-9fe95f9f\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-9fe95f9f\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-f23e69aa\" data-vce-do-apply=\"all el-f23e69aa\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-247ccd69\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-247ccd69\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-247ccd69\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first\" id=\"el-1e393ebf\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-1e393ebf\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-1e393ebf\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last\" id=\"el-45d28435\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-45d28435\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-45d28435\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\" data-vce-boxed-width=\"true\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-c8938696\" data-vce-do-apply=\"all el-c8938696\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-9d39a476\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-9d39a476\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-9d39a476\"><div class=\"vcv-row-control-wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Introducci\u00f3nProfec\u00eda y Servicio<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"template-page-builder.php","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2551","post","type-post","status-publish","format-standard","hentry","category-estudios-biblicos"],"_links":{"self":[{"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/posts\/2551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/comments?post=2551"}],"version-history":[{"count":2,"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/posts\/2551\/revisions"}],"predecessor-version":[{"id":2559,"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/posts\/2551\/revisions\/2559"}],"wp:attachment":[{"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/media?parent=2551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/categories?post=2551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calvarymaranatha.com\/en\/wp-json\/wp\/v2\/tags?post=2551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}